{"id":543,"date":"2022-04-28T14:55:04","date_gmt":"2022-04-28T12:55:04","guid":{"rendered":"https:\/\/adric-interculturel.com\/citoyennete\/?p=543"},"modified":"2022-04-28T16:52:34","modified_gmt":"2022-04-28T14:52:34","slug":"agir-en-faveur-de-legalite-femmes-hommes-dans-le-sport-loperation-sport-feminin-toujours","status":"publish","type":"post","link":"https:\/\/adric-interculturel.com\/citoyennete\/agir-en-faveur-de-legalite-femmes-hommes-dans-le-sport-loperation-sport-feminin-toujours-543\/","title":{"rendered":"Agir en faveur de l&#8217;\u00e9galit\u00e9 femmes-hommes dans le sport, l&#8217;op\u00e9ration Sport F\u00e9minin Toujours"},"content":{"rendered":"\nL\u2019objectif du projet Sport F\u00e9minin Toujours est de valoriser la pratique sportive f\u00e9minine et de combattre les st\u00e9r\u00e9otypes sexistes. Depuis de nombreuses ann\u00e9es, la question se pose de la repr\u00e9sentation des femmes dans la pratique sportive&nbsp;: le peu de retransmission des \u00e9v\u00e8nements sportifs f\u00e9minin dans les m\u00e9dias est un frein \u00e0 la pratique sportive des jeunes filles qui n\u2019ont pas de mod\u00e8les auxquels s\u2019identifier. Pour pallier ce d\u00e9ficit, le CSA, en partenariat avec le Minist\u00e8re des Sports et du Secr\u00e9taire d\u2019Etat charg\u00e9 de l\u2019Egalit\u00e9 entre les femmes et les hommes, a lanc\u00e9 cette op\u00e9ration pour promouvoir la f\u00e9minisation des rediffusions sportives, des plateaux de t\u00e9l\u00e9vision et des instances sportives.\n\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\nLe lancement du projet a permis d\u2019augmenter la part des rediffusions sportives consacr\u00e9es au sport f\u00e9minin de 10% \u00e0 20% entre 2012 et 2016. L\u2019op\u00e9ration est chaque ann\u00e9e l\u2019occasion de mettre en lumi\u00e8re sur le sport au f\u00e9minin, amateur et de haut niveau, et ses enjeux de repr\u00e9sentation, et peut-\u00eatre ainsi cr\u00e9er des vocations pour permettre l\u2019\u00e9mergence d\u2019une nouvelle g\u00e9n\u00e9ration de sportives.\n\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\nL\u2019\u00e9dition 2022 s\u2019est d\u00e9roul\u00e9e du 14 au 20 f\u00e9vrier, pendant les Jeux Olympiques d\u2019hiver, et s\u2019est accompagn\u00e9e d\u2019une campagne digitale sur les r\u00e9seaux sociaux, incitant les spectateur-trices \u00e0 participer \u00e0 la valorisation du sport f\u00e9minin en partageant une s\u00e9quence ou performance marquante, pour t\u00e9moigner de leur volont\u00e9 de voir plus d\u2019athl\u00e8tes et expertes f\u00e9minines \u00e0 l\u2019antenne.\n","protected":false},"excerpt":{"rendered":"<p>L\u2019objectif du projet Sport F\u00e9minin Toujours est de valoriser la pratique sportive f\u00e9minine et de combattre les st\u00e9r\u00e9otypes sexistes. Depuis de nombreuses ann\u00e9es, la question se pose de la repr\u00e9sentation des femmes dans la pratique sportive&nbsp;: le peu de retransmission des \u00e9v\u00e8nements sportifs f\u00e9minin dans les m\u00e9dias est un frein \u00e0 la pratique sportive des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":599,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[29],"tags":[],"_links":{"self":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/posts\/543"}],"collection":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/comments?post=543"}],"version-history":[{"count":18,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/posts\/543\/revisions"}],"predecessor-version":[{"id":638,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/posts\/543\/revisions\/638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/media\/599"}],"wp:attachment":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/media?parent=543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/categories?post=543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/tags?post=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}