{"id":22,"count":1,"description":"","link":"https:\/\/adric-interculturel.com\/citoyennete\/tag\/chiffres\/","name":"Chiffres","slug":"chiffres","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/tags\/22"}],"collection":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/adric-interculturel.com\/citoyennete\/wp-json\/wp\/v2\/posts?tags=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}